{"id":17234,"date":"2026-03-19T09:53:51","date_gmt":"2026-03-19T09:53:51","guid":{"rendered":"https:\/\/www.turismojesi.it\/aziende-locali-guide-naturalistiche\/"},"modified":"2026-06-17T13:31:01","modified_gmt":"2026-06-17T13:31:01","slug":"aziende-locali-guide-naturalistiche","status":"publish","type":"page","link":"https:\/\/www.turismojesi.it\/en\/aziende-locali-guide-naturalistiche\/","title":{"rendered":"Aziende Locali &#8211; GUIDE NATURALISTICHE"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"17234\" class=\"elementor elementor-17234 elementor-14529\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73568d2 elementor-section-height-min-height elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-items-middle\" data-id=\"73568d2\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cd39308\" data-id=\"cd39308\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31905cb elementor-widget elementor-widget-heading\" data-id=\"31905cb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">nature guides<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3900c38 elementor-widget elementor-widget-text-editor\" data-id=\"3900c38\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><p>Discover Jesi and its surrounding area through the eyes of our nature guides, exploring landscapes, biodiversity, and local stories.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f6a71b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f6a71b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"raven-column-link elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e75b98c\" data-raven-link=\"https:\/\/www.turismojesi.it\/trek-e-bike-di-maurizio-rinaldi\/\" data-raven-link-target=\"_self\" data-id=\"e75b98c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f9425a elementor-widget elementor-widget-ucaddon_zoom_caption_reveal_content_box\" data-id=\"0f9425a\" data-element_type=\"widget\" data-widget_type=\"ucaddon_zoom_caption_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Caption Reveal Content Box -->\n<style>\/* widget: Caption Reveal Content Box *\/\n\n#uc_zoom_caption_reveal_content_box_elementor_0f9425a *{\n  box-sizing:border-box;\n}\n#uc_zoom_caption_reveal_content_box_elementor_0f9425a{\n  position:relative;\n  overflow:hidden;\n  direction:ltr!important;\n}\n\n#uc_zoom_caption_reveal_content_box_elementor_0f9425a .ue-link{\n  display:block;\n  position:absolute;\n  left:0;\n  right:0;\n  bottom:0;\n  top:0;\n}\n\n#uc_zoom_caption_reveal_content_box_elementor_0f9425a .image-caption-reveal-on-hover{\n  transition:500ms;\n  width:100%;\n  background-color:lightgray;\n  background-image:url(https:\/\/www.turismojesi.it\/wp-content\/uploads\/2025\/10\/20250216_121936-Maurizio-Rinaldi-scaled.jpg);\n  background-size:cover;\n  position:absolute;\n  top:0;\n  left:0;\n  bottom:0;\n  right:0;\n  transform:scale(100%,100%);\n}\n\n#uc_zoom_caption_reveal_content_box_elementor_0f9425a .icroh-caption{\n  transition:500ms;\n  position:absolute;\n  color:white;\n  width:100%;\n}\n\n#uc_zoom_caption_reveal_content_box_elementor_0f9425a .icroh-text{\n  display:none;\n}\n#uc_zoom_caption_reveal_content_box_elementor_0f9425a.ue_crcb_active .icroh-text{\n  display:block;\n}\n\n\n.icroh-title{\n  font-size:18px;\n}\n\n\n<\/style>\n\n<div id=\"uc_zoom_caption_reveal_content_box_elementor_0f9425a\" class=\"zoom_caption_reveal_content_box\" role=\"region\" aria-labelledby=\"\">\n  <div class=\"image-caption-reveal-on-hover\">\n  <\/div>\n\n    <div class=\"icroh-caption\">\n      <div class=\"icroh-title\">Maurizio Rinaldi<\/div>      <div class=\"icroh-text\" aria-hidden=\"true\" ><\/div>\n    <\/div>\n  \n  \t\n  \n  \n<\/div>\n<!-- end Caption Reveal Content Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"raven-column-link elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-557b02a\" data-raven-link=\"https:\/\/www.turismojesi.it\/raffaela-gattini-guida-turistica\/\" data-raven-link-target=\"_self\" data-id=\"557b02a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f51649 elementor-widget elementor-widget-ucaddon_zoom_caption_reveal_content_box\" data-id=\"9f51649\" data-element_type=\"widget\" data-widget_type=\"ucaddon_zoom_caption_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Caption Reveal Content Box -->\n<style>\/* widget: Caption Reveal Content Box *\/\n\n#uc_zoom_caption_reveal_content_box_elementor_9f51649 *{\n  box-sizing:border-box;\n}\n#uc_zoom_caption_reveal_content_box_elementor_9f51649{\n  position:relative;\n  overflow:hidden;\n  direction:ltr!important;\n}\n\n#uc_zoom_caption_reveal_content_box_elementor_9f51649 .ue-link{\n  display:block;\n  position:absolute;\n  left:0;\n  right:0;\n  bottom:0;\n  top:0;\n}\n\n#uc_zoom_caption_reveal_content_box_elementor_9f51649 .image-caption-reveal-on-hover{\n  transition:500ms;\n  width:100%;\n  background-color:lightgray;\n  background-image:url(https:\/\/www.turismojesi.it\/wp-content\/uploads\/2026\/03\/Guide-Turistiche-scaled.jpg);\n  background-size:cover;\n  position:absolute;\n  top:0;\n  left:0;\n  bottom:0;\n  right:0;\n  transform:scale(100%,100%);\n}\n\n#uc_zoom_caption_reveal_content_box_elementor_9f51649 .icroh-caption{\n  transition:500ms;\n  position:absolute;\n  color:white;\n  width:100%;\n}\n\n#uc_zoom_caption_reveal_content_box_elementor_9f51649 .icroh-text{\n  display:none;\n}\n#uc_zoom_caption_reveal_content_box_elementor_9f51649.ue_crcb_active .icroh-text{\n  display:block;\n}\n\n\n.icroh-title{\n  font-size:18px;\n}\n\n\n<\/style>\n\n<div id=\"uc_zoom_caption_reveal_content_box_elementor_9f51649\" class=\"zoom_caption_reveal_content_box\" role=\"region\" aria-labelledby=\"\">\n  <div class=\"image-caption-reveal-on-hover\">\n  <\/div>\n\n    <div class=\"icroh-caption\">\n      <div class=\"icroh-title\">Raffaela Gattini<\/div>      <div class=\"icroh-text\" aria-hidden=\"true\" ><\/div>\n    <\/div>\n  \n  \t\n  \n  \n<\/div>\n<!-- end Caption Reveal Content Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"raven-column-link elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-157d4a2\" data-raven-link=\"https:\/\/www.turismojesi.it\/dove-mangiare-in-centro-ristoranti-pizzerie\/\" data-raven-link-target=\"_self\" data-id=\"157d4a2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c98b4f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c98b4f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"raven-column-link elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e11690a\" data-raven-link=\"https:\/\/www.turismojesi.it\/dove-mangiare-in-centro-trattorie\/\" data-raven-link-target=\"_self\" data-id=\"e11690a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"raven-column-link elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-448eedd\" data-raven-link=\"https:\/\/www.turismojesi.it\/cibariando-pesce-dintorni\/\" data-raven-link-target=\"_self\" data-id=\"448eedd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"raven-column-link elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5d8a512\" data-raven-link=\"https:\/\/www.turismojesi.it\/jack-rabbit\/\" data-raven-link-target=\"_self\" data-id=\"5d8a512\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>nature guides Discover Jesi and its surrounding area through the eyes of our nature guides, exploring landscapes, biodiversity, and local stories. Maurizio Rinaldi Raffaela Gattini<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-17234","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.turismojesi.it\/en\/wp-json\/wp\/v2\/pages\/17234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.turismojesi.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.turismojesi.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.turismojesi.it\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.turismojesi.it\/en\/wp-json\/wp\/v2\/comments?post=17234"}],"version-history":[{"count":3,"href":"https:\/\/www.turismojesi.it\/en\/wp-json\/wp\/v2\/pages\/17234\/revisions"}],"predecessor-version":[{"id":17238,"href":"https:\/\/www.turismojesi.it\/en\/wp-json\/wp\/v2\/pages\/17234\/revisions\/17238"}],"wp:attachment":[{"href":"https:\/\/www.turismojesi.it\/en\/wp-json\/wp\/v2\/media?parent=17234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}